{"id":2832,"date":"2025-02-04T18:27:30","date_gmt":"2025-02-04T18:27:30","guid":{"rendered":"https:\/\/autogenai.dsstaging2.com\/apac\/?page_id=2832"},"modified":"2025-08-07T11:23:03","modified_gmt":"2025-08-07T11:23:03","slug":"infrastructure-engineering","status":"publish","type":"page","link":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/","title":{"rendered":"Infrastructure &amp; Engineering"},"content":{"rendered":"<div class=\"m-wrapper  has-overflow container-fluid\" >\n\t    \n\t\n\t\n\t<div class=\"m-wrapper__inner\">\n\t\t\n<div class=\"m-banner m-banner--full  l-banner-hero overlay has-logo-slider has-overlay order-default\" >\n\n\t\n\t\n\t<div class=\"m-banner__container container-fluid\" style='--overlayOpacity: 100%;--columns-ratio: 52%;'>\n\n\t\t\n\t\t<div class=\"m-banner__inner container flex-left style-light\">\n\n\t\t\t<div class=\"l-banner \" style=\"\">\n\n\t\t\t\t\n<div class=\"l-banner__text\">\n        <div class=\"l-banner__inner text-left\">\n\n        <div class=\"c-heading -h2\">\n\t\t\t\n\t\t\t\t\t\t\t<h1  class=\"c-heading__title\">Fortifying Our Future<\/h1>\t\t\t\n\t\t\t        <\/div>\n\n\t\t            <div class=\"c-heading__description is-wysiwyg\">\n\t\t\t\t<p>AutogenAI is revolutionising the infrastructure and engineering sectors. From road and rail, to utilities and urban planning, to vital infrastructure and engineering consultancy &#8211; our clients are winning bids across the spectrum.<\/p>\n<p>Using AutogenAI, they&#8217;re accelerating their growth at an unprecedented rate.<\/p>\n<p>&nbsp;<\/p>\n            <\/div>\n\t\t    <\/div>\n    \t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/book-a-demo\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Book a Demo<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t\n\t\t\t<a href=\"\/apac\/contact\/\"  class=\"c-btn -normal -secondary \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Talk to Our Experts<\/span><\/span><\/a>\n\t\t    <\/div>\n\t\n\t<\/div>\n\n    <div class=\"l-banner__media\">\n\t    \t\t\t\t\t\n\t\t\t\t            <div class=\"c-image\">\n            <figure class=\"c-image__media c-image__primary\">\n                <img decoding=\"async\" class=\"c-image__src lazy\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/infraestructure-e1741614118318-1024x660.jpg\"  alt=\"infraestructure\" width=\"1024\" height=\"660\"\/>            <\/figure>\n        <\/div>\n    \n\t\t\t\n\t\t    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\n    <div class=\"scroll-down sd-left\">\n        <span class=\"scroll-down__txt\">\n            KEEP SCROLLING        <\/span>\n            <\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-marquee  gb-s container \" data-viewport=&#039;true&#039; data-viewport-repeat=&#039;true&#039; data-viewport-effect=&#039;none&#039; >\n\t\t\t\t        <div class=\"m-marquee__container\">\n            <p class=\"l-slider-images__title\">Trusted by<\/p>\n        <\/div>\n\t\t<div class=\"m-marquee__container\" data-slider-autoplay='true' data-viewport=\"true\" data-viewport-repeat=\"true\" style=\"--marquee-interval: 120s;--marquee-gap: 90px;--marquee-max-height: 90px;--marquee-max-width: 50px;\">\n\t\t<div class=\"m-marquee__wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\" loading=\"lazy\" alt=\"mtc logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\" loading=\"lazy\" alt=\"Grosvenor\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\" loading=\"lazy\" alt=\"Corstorphine Wright\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\" loading=\"lazy\" alt=\"EFG\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\" loading=\"lazy\" alt=\"lirohill color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\" loading=\"lazy\" alt=\"gafcon color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\" loading=\"lazy\" alt=\"mission first logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\" loading=\"lazy\" alt=\"hill logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\" loading=\"lazy\" alt=\"ooh logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\" loading=\"lazy\" alt=\"ripper corp logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\" loading=\"lazy\" alt=\"siemens logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\" loading=\"lazy\" alt=\"voi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\" loading=\"lazy\" alt=\"scci logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\" loading=\"lazy\" alt=\"prevista logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\" loading=\"lazy\" alt=\"omexus group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\" loading=\"lazy\" alt=\"pareto logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\" loading=\"lazy\" alt=\"priory healthcare logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\" loading=\"lazy\" alt=\"Roemer Barnes\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\" loading=\"lazy\" alt=\"step5 logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\" loading=\"lazy\" alt=\"sublet logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\" loading=\"lazy\" alt=\"tivoli logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\" loading=\"lazy\" alt=\"gei loog color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\" loading=\"lazy\" alt=\"whitehead logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\" loading=\"lazy\" alt=\"sureserve logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\" loading=\"lazy\" alt=\"ocu logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\" loading=\"lazy\" alt=\"nrs logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\" loading=\"lazy\" alt=\"nacro logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\" loading=\"lazy\" alt=\"murphy logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\" loading=\"lazy\" alt=\"mtc logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\" loading=\"lazy\" alt=\"msi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\" loading=\"lazy\" alt=\"mcr logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\" loading=\"lazy\" alt=\"m1 support logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\" loading=\"lazy\" alt=\"lmac logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\" loading=\"lazy\" alt=\"lifetime logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\" loading=\"lazy\" alt=\"itgl logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\" loading=\"lazy\" alt=\"irara logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\" loading=\"lazy\" alt=\"insequa ltd\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\" loading=\"lazy\" alt=\"infonetica logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\" loading=\"lazy\" alt=\"IFF color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\" loading=\"lazy\" alt=\"Hawking logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\" loading=\"lazy\" alt=\"Green Park Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\" loading=\"lazy\" alt=\"Graham Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\" loading=\"lazy\" alt=\"Fujitsu Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\" loading=\"lazy\" alt=\"Frontline Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\" loading=\"lazy\" alt=\"Fortress Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\" loading=\"lazy\" alt=\"bsi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\" loading=\"lazy\" alt=\"bswlogo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\" loading=\"lazy\" alt=\"Carnall Farrar 2 color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\" loading=\"lazy\" alt=\"Carium Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\" loading=\"lazy\" alt=\"Clarasys logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\" loading=\"lazy\" alt=\"diaverum logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\" loading=\"lazy\" alt=\"Everyturn Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\" loading=\"lazy\" alt=\"Favorite Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\" loading=\"lazy\" alt=\"breheny logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\" loading=\"lazy\" alt=\"Blue Star Color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\" loading=\"lazy\" alt=\"bellrock logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\" loading=\"lazy\" alt=\"bam logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\" loading=\"lazy\" alt=\"baily garner logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\" loading=\"lazy\" alt=\"auctus logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\" loading=\"lazy\" alt=\"atkins color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\" loading=\"lazy\" alt=\"arriva logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\" loading=\"lazy\" alt=\"am healthcare group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\" loading=\"lazy\" alt=\"4C Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\" loading=\"lazy\" alt=\"Bidding Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\" loading=\"lazy\" alt=\"mitie logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\" loading=\"lazy\" alt=\"Kate Hill Color Logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\" loading=\"lazy\" alt=\"specsavers color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\" loading=\"lazy\" alt=\"serco color 2\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\" loading=\"lazy\" alt=\"ADS Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"m-marquee__wrapper\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\" loading=\"lazy\" alt=\"mtc logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\" loading=\"lazy\" alt=\"Grosvenor\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\" loading=\"lazy\" alt=\"Corstorphine Wright\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\" loading=\"lazy\" alt=\"EFG\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\" loading=\"lazy\" alt=\"lirohill color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\" loading=\"lazy\" alt=\"gafcon color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\" loading=\"lazy\" alt=\"mission first logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\" loading=\"lazy\" alt=\"hill logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\" loading=\"lazy\" alt=\"ooh logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\" loading=\"lazy\" alt=\"ripper corp logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\" loading=\"lazy\" alt=\"siemens logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\" loading=\"lazy\" alt=\"voi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\" loading=\"lazy\" alt=\"scci logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\" loading=\"lazy\" alt=\"prevista logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\" loading=\"lazy\" alt=\"omexus group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\" loading=\"lazy\" alt=\"pareto logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\" loading=\"lazy\" alt=\"priory healthcare logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\" loading=\"lazy\" alt=\"Roemer Barnes\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\" loading=\"lazy\" alt=\"step5 logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\" loading=\"lazy\" alt=\"sublet logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\" loading=\"lazy\" alt=\"tivoli logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\" loading=\"lazy\" alt=\"gei loog color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\" loading=\"lazy\" alt=\"whitehead logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\" loading=\"lazy\" alt=\"sureserve logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\" loading=\"lazy\" alt=\"ocu logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\" loading=\"lazy\" alt=\"nrs logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\" loading=\"lazy\" alt=\"nacro logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\" loading=\"lazy\" alt=\"murphy logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\" loading=\"lazy\" alt=\"mtc logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\" loading=\"lazy\" alt=\"msi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\" loading=\"lazy\" alt=\"mcr logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\" loading=\"lazy\" alt=\"m1 support logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\" loading=\"lazy\" alt=\"lmac logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\" loading=\"lazy\" alt=\"lifetime logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\" loading=\"lazy\" alt=\"itgl logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\" loading=\"lazy\" alt=\"irara logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\" loading=\"lazy\" alt=\"insequa ltd\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\" loading=\"lazy\" alt=\"infonetica logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\" loading=\"lazy\" alt=\"IFF color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\" loading=\"lazy\" alt=\"Hawking logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\" loading=\"lazy\" alt=\"Green Park Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\" loading=\"lazy\" alt=\"Graham Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\" loading=\"lazy\" alt=\"Fujitsu Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\" loading=\"lazy\" alt=\"Frontline Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\" loading=\"lazy\" alt=\"Fortress Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\" loading=\"lazy\" alt=\"bsi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\" loading=\"lazy\" alt=\"bswlogo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\" loading=\"lazy\" alt=\"Carnall Farrar 2 color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\" loading=\"lazy\" alt=\"Carium Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\" loading=\"lazy\" alt=\"Clarasys logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\" loading=\"lazy\" alt=\"diaverum logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\" loading=\"lazy\" alt=\"Everyturn Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\" loading=\"lazy\" alt=\"Favorite Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\" loading=\"lazy\" alt=\"breheny logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\" loading=\"lazy\" alt=\"Blue Star Color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\" loading=\"lazy\" alt=\"bellrock logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\" loading=\"lazy\" alt=\"bam logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\" loading=\"lazy\" alt=\"baily garner logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\" loading=\"lazy\" alt=\"auctus logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\" loading=\"lazy\" alt=\"atkins color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\" loading=\"lazy\" alt=\"arriva logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\" loading=\"lazy\" alt=\"am healthcare group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\" loading=\"lazy\" alt=\"4C Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\" loading=\"lazy\" alt=\"Bidding Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\" loading=\"lazy\" alt=\"mitie logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\" loading=\"lazy\" alt=\"Kate Hill Color Logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\" loading=\"lazy\" alt=\"specsavers color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\" loading=\"lazy\" alt=\"serco color 2\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\" loading=\"lazy\" alt=\"ADS Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"m-slider m-slider-v3 l-slider-testimonials-2  gt gb-l has-pagination\"  >\n\t<div class=\"container\">\n\t\t<div class=\"m-slider__inner\">\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"m-slider__col l-slider-testimonials-nav\">\n\t\t\t\t<div class=\"l-slider-testimonials-nav__top\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"c-heading -h2\">\n\t\t\t\t\t\t\t<h2 class=\"c-heading__title\">Customer Testimonials<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"l-slider-testimonials-nav__bottom\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__nav\" style=\"\">\n    <div class=\"m-slider__arrows -prev swiper-button-prev\">\n        <svg class=\"arrow-icon\" height=\"30px\" width=\"30px\">\n            <use xlink:href=\"#lib-icon-arrow4\"><\/use>\n        <\/svg>\n    <\/div>\n    <div class=\"m-slider__arrows -next swiper-button-next\">\n        <svg class=\"arrow-icon\" height=\"30px\" width=\"30px\">\n            <use xlink:href=\"#lib-icon-arrow4\"><\/use>\n        <\/svg>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__pagination swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"m-slider__col\">\n\t\t\t\t<div class=\"m-slider__container swiper js-slider--with-nav js-slider-advanced\" data-slider-navigation='bottom-arrows' data-slider-pagination='progressbar' data-slider-leading-zero='true'>\n\t\t\t\t\t<div class=\"m-slider__wrapper swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco.jpeg\" class=\"attachment-full size-full\" alt=\"Mark Irwin Serco\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">\u201dThe first of our &#039;Impact Pilots&#039; aimed at enabling innovation in public services through our partnership with AutogenAI has already seen us use its functionality more than 6,000 times, generating significant knowledge content.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tMark Irwin\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Group Chief Executive at SERCO<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant.jpeg\" class=\"attachment-full size-full\" alt=\"Mark Sargeant\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">&quot;AutogenAI, not only elevated the quality of our bids, but it also increased the speed of responses, especially when faced with challenging questions.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tMark Sargeant\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Head of Business Development at Twin Training<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-slider l-slider-images  gt-s gb-s container \"  >\n\n\t<div class=\"m-slider__outer\">\n\n\t\t\n\t\t\n\t\t\n                    <div class=\"m-slider__container\">\n                <p class=\"l-slider-images__title\">The Highest Level of Security<\/p>\n            <\/div>\n        \n\t\t<div class=\"m-slider__container swiper js-slider-simple\" data-slider-columns='6' data-slider-columns-gap='20' data-slider-columns-mobile='2' data-slider-columns-mobile-gap='20' data-slider-leading-zero='true' data-slider-loop='true' data-slider-autoplay='true' data-slider-autoplay-delay='001' data-slider-autoplay-observer='1' data-slider-autoplay-speed='3000' data-slider-autoplay-continuously='1'>\n\t\t\t<div class=\"m-slider__wrapper swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t    <picture class=\"m-slide__media\">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/trusted-cloud.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/trusted-cloud.png\">\n\t\t\t\t\t\t\t\n\t\t\t                <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/trusted-cloud.png\">\n\t\t\t\t\t        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/trusted-cloud.png\" alt=\"Trusted Cloud Provider AutogenAI\">\n    <\/picture>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t    <picture class=\"m-slide__media\">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/AICPA-Logo-e1730485587658.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/AICPA-Logo-1024x1024.png\">\n\t\t\t\t\t\t\t\n\t\t\t                <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/AICPA-Logo-768x768.png\">\n\t\t\t\t\t        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/AICPA-Logo-e1730485587658.png\" alt=\"AICPA-Logo\">\n    <\/picture>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t    <picture class=\"m-slide__media\">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/TX-RAMP-seal.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/TX-RAMP-seal.png\">\n\t\t\t\t\t\t\t\n\t\t\t                <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/TX-RAMP-seal.png\">\n\t\t\t\t\t        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/TX-RAMP-seal.png\" alt=\"TX RAMP AutogenAI\">\n    <\/picture>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t    <picture class=\"m-slide__media\">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/gdpr-e1730485713623.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/gdpr-1024x1024.png\">\n\t\t\t\t\t\t\t\n\t\t\t                <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/gdpr-768x768.png\">\n\t\t\t\t\t        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/gdpr-e1730485713623.png\" alt=\"GDPR\">\n    <\/picture>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t    <picture class=\"m-slide__media\">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/star_360-removebg-preview.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/star_360-removebg-preview.png\">\n\t\t\t\t\t\t\t\n\t\t\t                <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/star_360-removebg-preview.png\">\n\t\t\t\t\t        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/star_360-removebg-preview.png\" alt=\"Star Level One\">\n    <\/picture>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t    <picture class=\"m-slide__media\">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/ccpa_360-removebg-preview.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/ccpa_360-removebg-preview.png\">\n\t\t\t\t\t\t\t\n\t\t\t                <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/ccpa_360-removebg-preview.png\">\n\t\t\t\t\t        <img decoding=\"async\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/ccpa_360-removebg-preview.png\" alt=\"CCPA\">\n    <\/picture>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide\">\n\t\t\t\t\t\t\t<div class=\"m-slide\">\n\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\n\t\t\n\t<\/div>\n\n<\/div>\n\n\n<div class=\"m-block  gt gb rcbl-custom-v1 l-content-1\"  >\n\n\t\n\t\n\t<div id=\"\" class=\"m-block__container container\"\n\t\tstyle=\"\">\n\n\t\t<div class=\"l-rcbl l-rcbl-v1\"\n\t\t\tstyle=\"--l-block-col: 1;--l-block-gap-vertical: 20px;--l-block-gap-horizontal: 20px;\">\n\t\t\t\t\t\t\n\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Tender Compliance in Seconds<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Pull out critical information from large documents in minutes.<br \/>\nGet a summary of the tender requirements in any format, immediately.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Secure Knowledge Management<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>The right data, to the right person, at the right time. Instantly find and use relevant<br \/>\nsnippets from text-dense documents hidden in your library. History-backed<br \/>\nintelligence ensures your responses are built from the freshest, most successful content.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Stress Free Collaboration<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Assign tasks and work on multiple projects simultaneously, in real-time, reducing<br \/>\nduplication of effort and ensuring a cohesive final bid &#8211; that&#8217;s delivered on time.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">The Toolbox of Your Dreams<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Expand text, summarise, check grammar, cut words, add case studies, insert statistics,<br \/>\nmaintain a consistent tone of voice, add win themes, translate into any language &#8211; in one click.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Never Lose on a Technicality<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Instantly review your proposal for relevance, evidence, grammar, and compliance. Our review<br \/>\nfeature ensures you\u2019re responding to the tender in the right way &#8211; the way that is best poised to win.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"l-rcbl__actions\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/book-a-demo\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Learn More<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\n<\/div>\n\n\n<div class=\"m-accordion  gt gb to-front l-accordion-v2\"  >\n\n\t\n\t\n\t<div class=\"m-accordion__container container\" style=\"\">\n\t\t<div class=\"l-accordion l-accordion-v1 order-reverse js-acc-wrapper icons-arrows\" style=\"--c-block-gl: 0px;--c-block-gr: 0px;--c-block-gt: 0px;--c-block-gb: 0px;--columns-ratio: 46%;\"  data-animation=\"js\"data-start-closed=\"true\">\n\n\t\t\t\n\t\t\t\t<div class=\"l-accordion__col l-accordion__content\">\n\n\t\t\t\t\t    <div class=\"c-heading -h2 \">\n\t\t\n\t\t            <div class=\"c-heading__pre\" >\n\t\t\t\tAutogenAI&#8217;s World-Class Assurance            <\/div>\n\t\t\n\t\t\t\t\t<h3  class=\"c-heading__title\">Our Pledge to Data Security<\/h3>\t\t\n\t\t    <\/div>\n\n<div class=\"c-heading__description is-wysiwyg\">\n\t\t\t<p>AutogenAI was designed specifically for the unique needs of organisations contracting with local, state, and federal governments.<\/p>\n<p>&nbsp;<\/p>\n<p>With 100+ security certifications, we adhere to the most stringent compliance standards, including CMMC 2.0, SOC2, ISO27001, ISO27017, GDPR, and DoD IL5 requirements, enabling us to handle controlled and classified data.<\/p>\n<p>&nbsp;<\/p>\n<p>Additionally, our ongoing evaluation of large language models (LLMs) guarantees optimal, tailored, and private results for your proposals, providing security for every situation. We do not use your data to train any LLMs, and we rigorously adhere to international privacy laws and industry best practices.<\/p>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"c-accordion c-accordion-v1\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n<div class=\"c-accordion__item js-acc-item\">\n\t\t\t\n\t\t<h3  class=\"c-accordion__title-wrap -h3\">        <button class=\"js-acc-button c-accordion__title\">\n\t\t\t\t\t\tWe have the most experience        <\/button>\n\t\t<\/h3>\t\n    <div class=\"js-acc-content\">\n\t\t\t\t            <div class=\"c-accordion__content\">\n                <div class=\"is-wysiwyg\">\n\t\t\t\t\t<p>AutogenAI launched in February 2022, before ChatGPT or any of our competitors. Today, we are one of the fastest growing AI companies.<\/p>\n                <\/div>\n\t\t\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t\n\t\t    <\/div>\n\t\t\t\t\t            <\/div>\n\t\t    <\/div>\n\n<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n<div class=\"c-accordion__item js-acc-item\">\n\t\t\t\n\t\t<h3  class=\"c-accordion__title-wrap -h3\">        <button class=\"js-acc-button c-accordion__title\">\n\t\t\t\t\t\tWe have an established Information Security Program        <\/button>\n\t\t<\/h3>\t\n    <div class=\"js-acc-content\">\n\t\t\t\t            <div class=\"c-accordion__content\">\n                <div class=\"is-wysiwyg\">\n\t\t\t\t\t<p>This covers our global business operations and is regularly reviewed and audited by independent third parties.<\/p>\n                <\/div>\n\t\t\t\t            <\/div>\n\t\t    <\/div>\n\n<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n<div class=\"c-accordion__item js-acc-item\">\n\t\t\t\n\t\t<h3  class=\"c-accordion__title-wrap -h3\">        <button class=\"js-acc-button c-accordion__title\">\n\t\t\t\t\t\tWe&#8217;re an open book        <\/button>\n\t\t<\/h3>\t\n    <div class=\"js-acc-content\">\n\t\t\t\t            <div class=\"c-accordion__content\">\n                <div class=\"is-wysiwyg\">\n\t\t\t\t\t<p>For any inquiries or to learn more about our security practices, please don&#8217;t hesitate to contact us or visit our Trust Center.<\/p>\n                <\/div>\n\t\t\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"https:\/\/trust.autogenai.com\/?_gl=1*mpf23q*_gcl_au*MTU1MDM2NTI1NS4xNzI3MTE4NjE4\" target=\"_blank\" class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Visit AutogenAI&#8217;s Trust Center<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t\t\t\t            <\/div>\n\t\t    <\/div>\n\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"https:\/\/trust.autogenai.com\/?_gl=1*mpf23q*_gcl_au*MTU1MDM2NTI1NS4xNzI3MTE4NjE4\" target=\"_blank\" class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Visit Our Trust Center<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"l-accordion__col l-accordion__media\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"c-accordion__media c-accordion__media--has-overlay is-sticky is-active\">\n\n\t\t\t\t\t\t\t\t<div class=\"c-image front-h-left front-v-center main-h-full main-v-center r-none is-video\">\n\n\t\t\t\t\t<div class=\"c-video__media c-video__primary\">\n\t\t\t\t\t\t\t\t\t\n\t\n    <video muted playsinline disablePictureInPicture  poster='https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/06\/Rectangle-10509-min.jpg' autoplay loop class=\"c-video lazy\">\n        <source data-src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/06\/7f36-49b8-a781-6a8f12e9b7a1-1.mp4\" type=\"video\/mp4\">\n    <\/video>\n\n\t\n\t\t\t\t\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-wrapper  gt gb wrapper-custom-v3 has-columns align-top container-fluid\" style='--wrap-col-1: 50%;--wrap-col-2: 50%;--wrap-col-gap: 20px;'>\n\t    \n\t\n\t\n\t<div class=\"m-wrapper__inner\">\n\t\t\n<div class=\"m-block  gt gb l-content-1\"  >\n\n\t\n\t\n\t<div id=\"\" class=\"m-block__container container\"\n\t\tstyle=\"\">\n\n\t\t<div class=\"l-rcbl l-rcbl-v1\"\n\t\t\tstyle=\"--l-block-col: 1;--l-block-gap-vertical: 20px;--l-block-gap-horizontal: 20px;\">\n\t\t\t<div class=\"m-banner__media\">\n\t\n    <video muted playsinline disablePictureInPicture  autoplay loop class=\"c-video lazy\">\n        <source data-src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/06\/1eff-4268-9559-2f9eecb53a67-1.mp4\" type=\"video\/mp4\">\n    <\/video>\n\n\t\n<\/div>\t\t\t\n\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t            <div class=\"c-block__pretitle\">\n                <span>70%<\/span>\n            <\/div>\n\t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Increase in drafting speed<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Get from blank page to an almost perfect draft in minutes.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/blog\/case-studies\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Read the Case Study<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t            <div class=\"c-block__pretitle\">\n                <span>85%<\/span>\n            <\/div>\n\t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Increase in productivity<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Streamline tasks, improve accuracy, and expedite the entire capture and proposal process. <\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/blog\/case-studies\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Read the Case Study<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t            <div class=\"c-block__pretitle\">\n                <span>241%<\/span>\n            <\/div>\n\t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Increase in win rates<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>elevate your efficiency and maximize your returns.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/blog\/case-studies\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Read the Case Study<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t            <div class=\"c-block__pretitle\">\n                <span>100%<\/span>\n            <\/div>\n\t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Increase in proposals submitted<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Improve the quality of your proposals at scale.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/blog\/case-studies\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Read the Case Study<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\n<\/div>\n\n\n<div class=\"m-block  gt gb is-sticky l-content-simple-1\"  >\n\n\t\n\t\n\t<div class=\"m-block__container container\" style=\"\">\n\n\t\t<div class=\"l-heading text-left l-heading-v1\">\n\n\t\t\t    <div class=\"c-heading -h2 \">\n\t\t\n\t\t\n\t\t\t\t\t<h2  class=\"c-heading__title\">Built for speed, scale, and competitive writing<\/h2>\t\t\n\t\t    <\/div>\n\n<div class=\"c-heading__description is-wysiwyg\">\n\t\t\t<p>Save significant prep and admin time with our innovative features that no other platform offers, allowing you to focus on crafting winning proposals.<\/p>\n\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/book-a-demo\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Book a Free Demo<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t\n\t\t\t\n\t\t    <\/div>\n\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"separators-custom-box  \"  >\n\n\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":0,"parent":722,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-2832","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AI Tools for Infrastructure &amp; Engineering | AutogenAI<\/title>\n<meta name=\"description\" content=\"AutogenAI is revolutionising the infrastructure and engineering sectors with AI tools. Our clients are winning bids across the spectrum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AutogenAI Federal | AI Solutions for Government Proposals\" \/>\n<meta property=\"og:description\" content=\"Streamline the proposal writing process, enhance compliance, and win more government contracts.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/\" \/>\n<meta property=\"og:site_name\" content=\"AutogenAI APAC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-08-07T11:23:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/10\/og-image-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"32 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/infrastructure-engineering\\\/\",\"url\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/infrastructure-engineering\\\/\",\"name\":\"AI Tools for Infrastructure & Engineering | AutogenAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/#website\"},\"datePublished\":\"2025-02-04T18:27:30+00:00\",\"dateModified\":\"2025-08-07T11:23:03+00:00\",\"description\":\"AutogenAI is revolutionising the infrastructure and engineering sectors with AI tools. Our clients are winning bids across the spectrum.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/infrastructure-engineering\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/infrastructure-engineering\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/infrastructure-engineering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sectors\",\"item\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Infrastructure &amp; Engineering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/#website\",\"url\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/\",\"name\":\"AutogenAI APAC\",\"description\":\"Win more business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AI Tools for Infrastructure & Engineering | AutogenAI","description":"AutogenAI is revolutionising the infrastructure and engineering sectors with AI tools. Our clients are winning bids across the spectrum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/","og_locale":"en_US","og_type":"article","og_title":"AutogenAI Federal | AI Solutions for Government Proposals","og_description":"Streamline the proposal writing process, enhance compliance, and win more government contracts.","og_url":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/","og_site_name":"AutogenAI APAC","article_modified_time":"2025-08-07T11:23:03+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/10\/og-image-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"32 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/","url":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/","name":"AI Tools for Infrastructure & Engineering | AutogenAI","isPartOf":{"@id":"https:\/\/autogenai.com\/apac\/#website"},"datePublished":"2025-02-04T18:27:30+00:00","dateModified":"2025-08-07T11:23:03+00:00","description":"AutogenAI is revolutionising the infrastructure and engineering sectors with AI tools. Our clients are winning bids across the spectrum.","breadcrumb":{"@id":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/autogenai.com\/apac\/sectors\/infrastructure-engineering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/autogenai.com\/apac\/"},{"@type":"ListItem","position":2,"name":"Sectors","item":"https:\/\/autogenai.com\/apac\/sectors\/"},{"@type":"ListItem","position":3,"name":"Infrastructure &amp; Engineering"}]},{"@type":"WebSite","@id":"https:\/\/autogenai.com\/apac\/#website","url":"https:\/\/autogenai.com\/apac\/","name":"AutogenAI APAC","description":"Win more business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autogenai.com\/apac\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/2832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/comments?post=2832"}],"version-history":[{"count":5,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/2832\/revisions"}],"predecessor-version":[{"id":4740,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/2832\/revisions\/4740"}],"up":[{"embeddable":true,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/722"}],"wp:attachment":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/media?parent=2832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}