{"id":4892,"date":"2025-09-02T02:38:41","date_gmt":"2025-09-02T02:38:41","guid":{"rendered":"https:\/\/autogenai.com\/apac\/?page_id=4892"},"modified":"2025-09-02T14:10:25","modified_gmt":"2025-09-02T14:10:25","slug":"ai-for-legal","status":"publish","type":"page","link":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/","title":{"rendered":"Legal"},"content":{"rendered":"<div class=\"m-wrapper  has-overflow container-fluid\" >\n\t    \n\t\n\t\n\t<div class=\"m-wrapper__inner\">\n\t\t\n<div class=\"m-banner m-banner--full  l-banner-hero overlay has-logo-slider has-overlay order-default\" >\n\n\t\n\t\n\t<div class=\"m-banner__container container-fluid\" style='--overlayOpacity: 100%;--columns-ratio: 52%;'>\n\n\t\t\n\t\t<div class=\"m-banner__inner container flex-left style-light\">\n\n\t\t\t<div class=\"l-banner \" style=\"\">\n\n\t\t\t\t\n<div class=\"l-banner__text\">\n        <div class=\"l-banner__inner text-left\">\n\n        <div class=\"c-heading -h2\">\n\t\t\t\n\t\t\t\t\t\t\t<h1  class=\"c-heading__title\"> AI for Legal<\/h1>\t\t\t\n\t\t\t                <div class=\"c-heading__sub\">Win More Work, Reduce Partner Hours, Deliver Pitches 85% Faster<\/div>\n\t\t\t        <\/div>\n\n\t\t            <div class=\"c-heading__description is-wysiwyg\">\n\t\t\t\t<p>Law firms are under constant pressure to deliver compelling pitches, win more work, and respond faster to client demands. Clients expect persuasive, evidence-backed proposals and directory submissions on tight deadlines, while partners and BD teams are already stretched to capacity.<\/p>\n<p><strong>AutogenAI<\/strong> gives your firm the ability to produce high-quality proposals, pitches, and legal directory submissions in a fraction of the time, freeing partners to focus on billable work and client relationships.<\/p>\n            <\/div>\n\t\t    <\/div>\n    \t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/book-a-demo\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Book a Demo<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t\n\t\t\t\n\t\t    <\/div>\n\t\n\t<\/div>\n\n    <div class=\"l-banner__media\">\n\t    \t\t\t\t\t\n\t\t\t\t            <div class=\"c-image\">\n            <figure class=\"c-image__media c-image__primary\">\n                <img decoding=\"async\" class=\"c-image__src lazy\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/09\/resizable_c8465690-51c6-4e3b-9af0-067a3fcd55b0-768x512.png\"  alt=\"resizable_c8465690-51c6-4e3b-9af0-067a3fcd55b0\" width=\"768\" height=\"512\"\/>            <\/figure>\n        <\/div>\n    \n\t\t\t\n\t\t    <\/div>\n\n\t\t\t<\/div>\n\n\t\t\t\n    <div class=\"scroll-down sd-left\">\n        <span class=\"scroll-down__txt\">\n            KEEP SCROLLING        <\/span>\n            <\/div>\n\n\t\t<\/div>\n\t<\/div>\n\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-marquee  gb-s container \" data-viewport=&#039;true&#039; data-viewport-repeat=&#039;true&#039; data-viewport-effect=&#039;none&#039; >\n\t\t\t\t        <div class=\"m-marquee__container\">\n            <p class=\"l-slider-images__title\">Trusted by<\/p>\n        <\/div>\n\t\t<div class=\"m-marquee__container\" data-slider-autoplay='true' data-viewport=\"true\" data-viewport-repeat=\"true\" style=\"--marquee-interval: 120s;--marquee-gap: 90px;--marquee-max-height: 90px;--marquee-max-width: 50px;\">\n\t\t<div class=\"m-marquee__wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\" loading=\"lazy\" alt=\"mtc logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\" loading=\"lazy\" alt=\"Grosvenor\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\" loading=\"lazy\" alt=\"Corstorphine Wright\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\" loading=\"lazy\" alt=\"EFG\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\" loading=\"lazy\" alt=\"lirohill color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\" loading=\"lazy\" alt=\"gafcon color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\" loading=\"lazy\" alt=\"mission first logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\" loading=\"lazy\" alt=\"hill logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\" loading=\"lazy\" alt=\"ooh logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\" loading=\"lazy\" alt=\"ripper corp logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\" loading=\"lazy\" alt=\"siemens logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\" loading=\"lazy\" alt=\"voi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\" loading=\"lazy\" alt=\"scci logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\" loading=\"lazy\" alt=\"prevista logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\" loading=\"lazy\" alt=\"omexus group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\" loading=\"lazy\" alt=\"pareto logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\" loading=\"lazy\" alt=\"priory healthcare logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\" loading=\"lazy\" alt=\"Roemer Barnes\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\" loading=\"lazy\" alt=\"step5 logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\" loading=\"lazy\" alt=\"sublet logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\" loading=\"lazy\" alt=\"tivoli logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\" loading=\"lazy\" alt=\"gei loog color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\" loading=\"lazy\" alt=\"whitehead logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\" loading=\"lazy\" alt=\"sureserve logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\" loading=\"lazy\" alt=\"ocu logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\" loading=\"lazy\" alt=\"nrs logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\" loading=\"lazy\" alt=\"nacro logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\" loading=\"lazy\" alt=\"murphy logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\" loading=\"lazy\" alt=\"mtc logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\" loading=\"lazy\" alt=\"msi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\" loading=\"lazy\" alt=\"mcr logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\" loading=\"lazy\" alt=\"m1 support logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\" loading=\"lazy\" alt=\"lmac logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\" loading=\"lazy\" alt=\"lifetime logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\" loading=\"lazy\" alt=\"itgl logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\" loading=\"lazy\" alt=\"irara logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\" loading=\"lazy\" alt=\"insequa ltd\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\" loading=\"lazy\" alt=\"infonetica logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\" loading=\"lazy\" alt=\"IFF color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\" loading=\"lazy\" alt=\"Hawking logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\" loading=\"lazy\" alt=\"Green Park Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\" loading=\"lazy\" alt=\"Graham Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\" loading=\"lazy\" alt=\"Fujitsu Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\" loading=\"lazy\" alt=\"Frontline Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\" loading=\"lazy\" alt=\"Fortress Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\" loading=\"lazy\" alt=\"bsi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\" loading=\"lazy\" alt=\"bswlogo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\" loading=\"lazy\" alt=\"Carnall Farrar 2 color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\" loading=\"lazy\" alt=\"Carium Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\" loading=\"lazy\" alt=\"Clarasys logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\" loading=\"lazy\" alt=\"diaverum logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\" loading=\"lazy\" alt=\"Everyturn Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\" loading=\"lazy\" alt=\"Favorite Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\" loading=\"lazy\" alt=\"breheny logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\" loading=\"lazy\" alt=\"Blue Star Color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\" loading=\"lazy\" alt=\"bellrock logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\" loading=\"lazy\" alt=\"bam logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\" loading=\"lazy\" alt=\"baily garner logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\" loading=\"lazy\" alt=\"auctus logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\" loading=\"lazy\" alt=\"atkins color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\" loading=\"lazy\" alt=\"arriva logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\" loading=\"lazy\" alt=\"am healthcare group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\" loading=\"lazy\" alt=\"4C Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\" loading=\"lazy\" alt=\"Bidding Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\" loading=\"lazy\" alt=\"mitie logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\" loading=\"lazy\" alt=\"Kate Hill Color Logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\" loading=\"lazy\" alt=\"specsavers color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\" loading=\"lazy\" alt=\"serco color 2\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\" loading=\"lazy\" alt=\"ADS Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<div class=\"m-marquee__wrapper\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color-1.png\" loading=\"lazy\" alt=\"mtc logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Grosvenor.png\" loading=\"lazy\" alt=\"Grosvenor\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/Corstorphine-Wright.png\" loading=\"lazy\" alt=\"Corstorphine Wright\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/EFG.png\" loading=\"lazy\" alt=\"EFG\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lirohill-color.png\" loading=\"lazy\" alt=\"lirohill color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gafcon-color.png\" loading=\"lazy\" alt=\"gafcon color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mission-first-logo-color.png\" loading=\"lazy\" alt=\"mission first logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/hill-logo-color.png\" loading=\"lazy\" alt=\"hill logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ooh-logo-color.png\" loading=\"lazy\" alt=\"ooh logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ripper-corp-logo.png\" loading=\"lazy\" alt=\"ripper corp logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/siemens-logo-color.png\" loading=\"lazy\" alt=\"siemens logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/voi-logo-color.png\" loading=\"lazy\" alt=\"voi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/scci-logo-color.png\" loading=\"lazy\" alt=\"scci logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/prevista-logo-color.png\" loading=\"lazy\" alt=\"prevista logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/omexus-group-logo-color.png\" loading=\"lazy\" alt=\"omexus group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/pareto-logo-color.png\" loading=\"lazy\" alt=\"pareto logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/priory-healthcare-logo-color.png\" loading=\"lazy\" alt=\"priory healthcare logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Roemer-Barnes.png\" loading=\"lazy\" alt=\"Roemer Barnes\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/step5-logo-color.png\" loading=\"lazy\" alt=\"step5 logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sublet-logo-color.png\" loading=\"lazy\" alt=\"sublet logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/tivoli-logo-color.png\" loading=\"lazy\" alt=\"tivoli logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/gei-loog-color.png\" loading=\"lazy\" alt=\"gei loog color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/whitehead-logo-color.png\" loading=\"lazy\" alt=\"whitehead logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/sureserve-logo-color.png\" loading=\"lazy\" alt=\"sureserve logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ocu-logo-color.png\" loading=\"lazy\" alt=\"ocu logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nrs-logo-color.png\" loading=\"lazy\" alt=\"nrs logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/nacro-logo-color.png\" loading=\"lazy\" alt=\"nacro logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/murphy-logo-color.png\" loading=\"lazy\" alt=\"murphy logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mtc-logo-color.png\" loading=\"lazy\" alt=\"mtc logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/msi-logo-color.png\" loading=\"lazy\" alt=\"msi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mcr-logo-color.png\" loading=\"lazy\" alt=\"mcr logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/m1-support-logo-color.png\" loading=\"lazy\" alt=\"m1 support logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lmac-logo-color.png\" loading=\"lazy\" alt=\"lmac logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/lifetime-logo-color.png\" loading=\"lazy\" alt=\"lifetime logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/itgl-logo-color.png\" loading=\"lazy\" alt=\"itgl logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/irara-logo-color.png\" loading=\"lazy\" alt=\"irara logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/insequa-ltd.png\" loading=\"lazy\" alt=\"insequa ltd\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/infonetica-logo-color.png\" loading=\"lazy\" alt=\"infonetica logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/IFF-color-logo.png\" loading=\"lazy\" alt=\"IFF color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Hawking-logo-color-1.png\" loading=\"lazy\" alt=\"Hawking logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Green-Park-Logo-Color.png\" loading=\"lazy\" alt=\"Green Park Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Graham-Logo-Color.png\" loading=\"lazy\" alt=\"Graham Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fujitsu-Logo-Color.png\" loading=\"lazy\" alt=\"Fujitsu Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Frontline-Logo-Color.png\" loading=\"lazy\" alt=\"Frontline Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Fortress-Logo-Color.png\" loading=\"lazy\" alt=\"Fortress Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bsi-logo-color.png\" loading=\"lazy\" alt=\"bsi logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bswlogo.png\" loading=\"lazy\" alt=\"bswlogo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carnall-Farrar-2-color-logo.png\" loading=\"lazy\" alt=\"Carnall Farrar 2 color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Carium-Logo-Color.png\" loading=\"lazy\" alt=\"Carium Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Clarasys-logo-color.png\" loading=\"lazy\" alt=\"Clarasys logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/diaverum-logo-color.png\" loading=\"lazy\" alt=\"diaverum logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Everyturn-Logo-Color.png\" loading=\"lazy\" alt=\"Everyturn Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Favorite-Logo-Color.png\" loading=\"lazy\" alt=\"Favorite Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/breheny-logo-color-1.png\" loading=\"lazy\" alt=\"breheny logo color (1)\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Blue-Star-Color-logo.png\" loading=\"lazy\" alt=\"Blue Star Color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bellrock-logo-color.png\" loading=\"lazy\" alt=\"bellrock logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/bam-logo-color.png\" loading=\"lazy\" alt=\"bam logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/baily-garner-logo-color.png\" loading=\"lazy\" alt=\"baily garner logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/auctus-logo-color.png\" loading=\"lazy\" alt=\"auctus logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/atkins-color-logo.png\" loading=\"lazy\" alt=\"atkins color logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/arriva-logo-color.png\" loading=\"lazy\" alt=\"arriva logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/am-healthcare-group-logo-color.png\" loading=\"lazy\" alt=\"am healthcare group logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/4C-Logo-Color.png\" loading=\"lazy\" alt=\"4C Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Bidding-Logo-Color.png\" loading=\"lazy\" alt=\"Bidding Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/mitie-logo-color.png\" loading=\"lazy\" alt=\"mitie logo color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/Kate-Hill-Color-Logo.png\" loading=\"lazy\" alt=\"Kate Hill Color Logo\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/specsavers-color.png\" loading=\"lazy\" alt=\"specsavers color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/serco-color-2.png\" loading=\"lazy\" alt=\"serco color 2\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-marquee__slide\">\n\t\t\t\t\t\t    <picture class=\"c-picture \">\n\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 1500px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 768px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t\t\t                    <source media=\"(min-width: 300px)\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\">\n\t\t\t\t\t\t\t\t\t        <img decoding=\"async\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/ADS-Logo-Color.png\" loading=\"lazy\" alt=\"ADS Logo Color\">\n    <\/picture>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\n<div class=\"m-slider m-slider-v3 l-slider-testimonials-2  gt gb-l has-pagination\"  >\n\t<div class=\"container\">\n\t\t<div class=\"m-slider__inner\">\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"m-slider__col l-slider-testimonials-nav\">\n\t\t\t\t<div class=\"l-slider-testimonials-nav__top\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"c-heading -h2\">\n\t\t\t\t\t\t\t<h2 class=\"c-heading__title\">Customer Testimonials<\/h2>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<div class=\"l-slider-testimonials-nav__bottom\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__nav\" style=\"\">\n    <div class=\"m-slider__arrows -prev swiper-button-prev\">\n        <svg class=\"arrow-icon\" height=\"30px\" width=\"30px\">\n            <use xlink:href=\"#lib-icon-arrow4\"><\/use>\n        <\/svg>\n    <\/div>\n    <div class=\"m-slider__arrows -next swiper-button-next\">\n        <svg class=\"arrow-icon\" height=\"30px\" width=\"30px\">\n            <use xlink:href=\"#lib-icon-arrow4\"><\/use>\n        <\/svg>\n    <\/div>\n<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__pagination swiper-pagination\"><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/div>\n\n\t\t\t<div class=\"m-slider__col\">\n\t\t\t\t<div class=\"m-slider__container swiper js-slider--with-nav js-slider-advanced\" data-slider-navigation='bottom-arrows' data-slider-pagination='progressbar' data-slider-leading-zero='true'>\n\t\t\t\t\t<div class=\"m-slider__wrapper swiper-wrapper\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/James.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/James.jpg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/James-300x300.jpg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/James-150x150.jpg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/James-200x200.jpg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">&quot;AutogenAl is a game changer when time is of the essence. Recently, it transformed our 2-3 week grant application process into a one-week turnaround without compromising on quality. In seconds, it utilised our library and approach outline to template a response, which set the stage for us to build upon.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tJames Walters FIEP\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">General Manager &#8211; Strategic Growth at MTC Future Ready<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"372\" height=\"395\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/trent-miller-e1743531705159.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/trent-miller-e1743531705159.jpeg 372w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/trent-miller-e1743531705159-283x300.jpeg 283w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/trent-miller-e1743531705159-188x200.jpeg 188w\" sizes=\"auto, (max-width: 372px) 100vw, 372px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">\u201dAutogenAI has enhanced both the speed and quality of our bid writing. It enables us to synthesise grant objectives, leverage external resources, and tap into our internal knowledge base to assess alignment with funding opportunities. As a result, we can craft compelling narratives that strengthen our bids and also support the strategic scaling of our organisation.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tTrent Miller\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">CEO at Youth Projects<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/Glen-Marshall.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/Glen-Marshall.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/Glen-Marshall-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/Glen-Marshall-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/Glen-Marshall-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">\u201dAutogenAI has significantly de-risked our internal key-man IP by ensuring we have an accessible repository of our technical solutions created over the past two decades. The ability to tap that traditionally tightly-held knowledge source is revolutionary for our business.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tGlenn Marshall\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Chief Executive Officer at AMS Group<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/1740756294698.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/1740756294698.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/1740756294698-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/1740756294698-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/03\/1740756294698-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">\u201dThe AutogenAI team has been super to deal with throughout our trial and onboarding. They have made a huge effort to answer all our questions promptly and support our team to get the most out of the tool. Although we are in the early stages of integrating the tool into our workflows, we see immense value and efficiency gains already.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tKirby Delamont\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Bid Director at oOh! Media<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco.jpeg\" class=\"attachment-full size-full\" alt=\"Mark Irwin Serco\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/mark-irwin-serco-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">\u201dThe first of our &#039;Impact Pilots&#039; aimed at enabling innovation in public services through our partnership with AutogenAI has already seen us use its functionality more than 6,000 times, generating significant knowledge content.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tMark Irwin\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Group Chief Executive at SERCO<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant.jpeg\" class=\"attachment-full size-full\" alt=\"Mark Sargeant\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Mark-Sargeant-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">&quot;AutogenAI, not only elevated the quality of our bids, but it also increased the speed of responses, especially when faced with challenging questions.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tMark Sargeant\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Head of Business Development at Twin Training<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"698\" height=\"804\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Screenshot-2024-09-24-at-2.01.05\u202fPM.jpg\" class=\"attachment-full size-full\" alt=\"AutogenAI\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Screenshot-2024-09-24-at-2.01.05\u202fPM.jpg 698w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Screenshot-2024-09-24-at-2.01.05\u202fPM-260x300.jpg 260w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/Screenshot-2024-09-24-at-2.01.05\u202fPM-174x200.jpg 174w\" sizes=\"auto, (max-width: 698px) 100vw, 698px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">\u201dHaving implemented AutogenAI, it is clear that this is a game changer; significantly increasing the productivity of bid teams.\u201d<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tDebbie Brockbank\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">Growth Director at HGS<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"400\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/chris-at-MEGT.jpeg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/chris-at-MEGT.jpeg 400w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/chris-at-MEGT-300x300.jpeg 300w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/chris-at-MEGT-150x150.jpeg 150w, https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/04\/chris-at-MEGT-200x200.jpeg 200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">&quot;AutogenAl has transformed the way we approach tender submissions in Australia. AutogenAl has significantly enhanced both the quantity and quality of our submissions, streamlining processes and improving accuracy. AutogenAl has enabled us to manage complex tenders with confidence, it saves us countless hours and is increasing our success rate.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tChristopher Dale\t\t<\/div>\n\n\t\t\t\t\t<span class=\"c-cite__company\">General Manager, Strategy and Design at MEGT<\/span>\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"m-slider__slide swiper-slide -v1\">\n\t\t\t\t\t\t\t\t\t\n<div class=\"container l-testimonials l-testimonials-v2  order-default text-left align-top\" style=\"\n--c-block-radius:0px; --c-block-gl: 0%;--c-block-gr: 0%;--c-block-gt: 0%;--c-block-gb: 0%;--columns-ratio: 100%;--c-txt-gl: 0px; --c-txt-gr: 0px; --c-txt-gt: 0px; --c-txt-gb: 0px;\">\n\n\t\n\t<div class=\"l-testimonials__col l-testimonials__text\">\n\t\t<blockquote class=\"c-testimonials\">\n\t\t\t<div class=\"c-citequote-order-default c-cite-v2\">\n\t\t\t<div class=\"c-photo c-cite__photo\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1\" height=\"1\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2024\/09\/salesforce-with-type-logo.svg\" class=\"attachment-full size-full\" alt=\"Salesforce\" \/>\t<\/div>\n\n\t\t\t\t<cite class=\"c-cite__content\">\n\t\t\t\t\t\t\t<p class=\"c-cite__text\">&quot;The world&#039;s leading AI bid-writing engine.&quot;<\/p>\n\t\t\t\t\t\t\t\t<\/cite>\n\t\t<div class=\"c-cite__profile\">\n\t\t\t<div class=\"c-cite__author\">\n\t\t<div class=\"c-cite__name\">\n\t\t\tSalesforce\t\t<\/div>\n\n\t\t\t<\/div>\n\t\t<\/div>\n\n<\/div>\n\t\t<\/blockquote>\n\t<\/div>\n\n<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-block  gt gb -colors-inverted l-content-simple-1\"  style='background-color: #2b3c57;color: #ffffff;'>\n\n\t\n\t\n\t<div class=\"m-block__container container\" style=\"\">\n\n\t\t<div class=\"l-heading text-left l-heading-v2\">\n\n\t\t\t    <div class=\"c-heading -h2 \">\n\t\t\n\t\t\n\t\t\t\t\t<h2  class=\"c-heading__title\">Proven results with leading law firms.<\/h2>\t\t\n\t\t    <\/div>\n\n<div class=\"c-heading__description is-wysiwyg\">\n\t\t\t<p><strong>50% reduction <\/strong>in partner input on proposals.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>85% efficiency gain<\/strong> for BD and bid teams across pitches, pursuits, proposals and directory submissions.<\/p>\n<p>&nbsp;<\/p>\n\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"https:\/\/autogenai.com\/blog\/case-studies\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Read the Case Studies<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n<\/div>\n\n\n<div class=\"m-wrapper  gt gb has-columns align-top container-fluid\" style='--wrap-col-1: 50%;--wrap-col-2: 50%;--wrap-col-gap: 20px;'>\n\t    \n\t\n\t\n\t<div class=\"m-wrapper__inner\">\n\t\t\n<div class=\"m-block  gt gb l-content-simple-1\"  >\n\n\t\n\t\n\t<div class=\"m-block__container container\" style=\"\">\n\n\t\t<div class=\"l-heading text-left l-heading-v1\">\n\n\t\t\t    <div class=\"c-heading -h2 \">\n\t\t\n\t\t\n\t\t\t\t\t<h2  class=\"c-heading__title\">Built for the Legal Sector<\/h2>\t\t\n\t\t    <\/div>\n\n<div class=\"c-heading__description is-wysiwyg\">\n\t\t\t<p>Unlike generic AI tools, AutogenAI is purpose-built for the complex, high-stakes world of legal proposals. Our platform is trained to produce compelling, structured and evidence-led content that speaks your client\u2019s language.<\/p>\n\t\t\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n<\/div>\n\n\n<div class=\"m-block  gt gb rcbl-custom-v1 l-content-1\"  >\n\n\t\n\t\n\t<div id=\"\" class=\"m-block__container container\"\n\t\tstyle=\"\">\n\n\t\t<div class=\"l-rcbl l-rcbl-v1\"\n\t\t\tstyle=\"--l-block-col: 1;--l-block-gap-vertical: 20px;--l-block-gap-horizontal: 20px;\">\n\t\t\t\t\t\t\n\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Pitch &#038; <br>proposal drafting.<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>From initial pursuits to formal bids, generate a persuasive, tailored first draft in minutes.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Legal directory submissions.<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Streamline submissions to Chambers &#038; Partners,<br \/>\nLegal 500, and other directories, driving efficiency<br \/>\nwhile safeguarding accuracy and compliance.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Lawyer CVs <br>&#038; bios.<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Create tailored, role-specific<br \/>\nbios for tenders and proposals.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">RFP &#038; tender responses.<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Extract requirements from complex RFPs and<br \/>\nproduce clear, relevant and competitive responses.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t                    <div class=\"l-rcbl__col\">\n\t\t\t\t\t\t\n<article class=\"c-block  c-block-v1 is-vertical text-left align-top\" style=\"--c-block-gap-vertical:0px;--c-block-gap-horizontal:0px;\">\n\n\t\n\t\n    <div class=\"c-block__body\" >\n\t    \t\t\n\t\t\t\t\t<h3  class=\"c-block__title\">Thought leadership &#038; <br>capability statements.<\/h3>\t\t\n\t\t\t\t\t                <div class=\"c-block__description\">\n\t\t\t\t\t<p>Genrate client-ready content<br \/>\nthat showcases your firm\u2019s expertise.<\/p>\n                <\/div>\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t\n\t\t\t        \n    <\/div>\n\n<\/article>\n                    <\/div>\n\t\t\t\t\t\n\t\t\t\t\t<\/div>\n\n\t\t\t<\/div>\n\n\t\n<\/div>\n\n\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-accordion  gt gb -colors-inverted to-front l-accordion-v2\"  style='background-color: #2b3c57;'>\n\n\t\n\t\n\t<div class=\"m-accordion__container container\" style=\"\">\n\t\t<div class=\"l-accordion l-accordion-v1 order-reverse js-acc-wrapper icons-arrows\" style=\"--c-block-gl: 0px;--c-block-gr: 0px;--c-block-gt: 0px;--c-block-gb: 0px;--columns-ratio: 46%;\"  data-animation=\"js\"data-start-closed=\"true\">\n\n\t\t\t\n\t\t\t\t<div class=\"l-accordion__col l-accordion__content\">\n\n\t\t\t\t\t    <div class=\"c-heading -h2 \">\n\t\t\n\t\t\n\t\t\t\t\t<h3  class=\"c-heading__title\">Real Results<\/h3>\t\t\n\t\t    <\/div>\n\n<div class=\"c-heading__description is-wysiwyg\">\n\t\t\t<p>A leading multinational law firm was struggling with declining win rates and excessive partner time spent on proposals. They trialled several tools including Responsive, Qvidian, Loopio and Copilot, but none delivered the quality, structure or persuasive depth they needed.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>The result:<\/strong>\u00a0Higher-quality proposals, faster turnaround and more wins without overburdening your partners.<\/p>\n\t\t<\/div>\n\n\t\t\t\t\t<div class=\"c-accordion c-accordion-v1\">\n\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n<div class=\"c-accordion__item js-acc-item\">\n\t\t\t\n\t\t<h3  class=\"c-accordion__title-wrap -h3\">        <button class=\"js-acc-button c-accordion__title\">\n\t\t\t\t\t\tWhy They Chose AutogenAI:        <\/button>\n\t\t<\/h3>\t\n    <div class=\"js-acc-content\">\n\t\t\t\t            <div class=\"c-accordion__content\">\n                <div class=\"is-wysiwyg\">\n\t\t\t\t\t<h5><\/h5>\n<p>&nbsp;<\/p>\n<ul>\n<li>\n<h5>\u00a0AI-first design, built specifically for high-quality proposal writing rather than generic content storage.<\/h5>\n<\/li>\n<li>\n<h5>Market-leading text quality, producing evidenced, persuasive and structured content every time.<\/h5>\n<\/li>\n<li>\n<h5>Easy adoption, with an intuitive interface enabling rapid onboarding and minimal disruption.<\/h5>\n<\/li>\n<\/ul>\n                <\/div>\n\t\t\t\t\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t\n\t\t    <\/div>\n\t\t\t\t\t            <\/div>\n\t\t    <\/div>\n\n<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n<div class=\"c-accordion__item js-acc-item\">\n\t\t\t\n\t\t<h3  class=\"c-accordion__title-wrap -h3\">        <button class=\"js-acc-button c-accordion__title\">\n\t\t\t\t\t\tThe Impact:        <\/button>\n\t\t<\/h3>\t\n    <div class=\"js-acc-content\">\n\t\t\t\t            <div class=\"c-accordion__content\">\n                <div class=\"is-wysiwyg\">\n\t\t\t\t\t<h5><\/h5>\n<p>&nbsp;<\/p>\n<ul>\n<li>\n<h5>First draft creation time cut from hours to minutes.<\/h5>\n<\/li>\n<li>\n<h5>Partner input reduced by 50 percent, freeing them for client-facing work.<\/h5>\n<\/li>\n<li>\n<h5>85 percent efficiency gains across pitches, proposals and directory submissions.<\/h5>\n<\/li>\n<\/ul>\n                <\/div>\n\t\t\t\t            <\/div>\n\t\t    <\/div>\n\n<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\n<div class=\"c-accordion__item js-acc-item\">\n\t\t\t\n\t\t<h3  class=\"c-accordion__title-wrap -h3\">        <button class=\"js-acc-button c-accordion__title\">\n\t\t\t\t\t\tWhy Leading Firms Trust AutogenAI:        <\/button>\n\t\t<\/h3>\t\n    <div class=\"js-acc-content\">\n\t\t\t\t            <div class=\"c-accordion__content\">\n                <div class=\"is-wysiwyg\">\n\t\t\t\t\t<h5><\/h5>\n<p>&nbsp;<\/p>\n<ul>\n<li>\n<h5>Sector expertise, developed with input from legal bid teams and partners.<\/h5>\n<\/li>\n<li>\n<h5>Unmatched AI depth, with over 100,000 hours of development optimised across 16 LLMs.<\/h5>\n<\/li>\n<li>\n<h5>Human-in-the-loop, combining the speed of AI with the expertise of your lawyers and BD team.<\/h5>\n<\/li>\n<\/ul>\n                <\/div>\n\t\t\t\t            <\/div>\n\t\t    <\/div>\n\n<\/div>\n\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"https:\/\/autogenai.com\/apac\/book-a-demo\/\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Speak to Our Legal Specialists<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t    <\/div>\n\t\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"l-accordion__col l-accordion__media\">\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"c-accordion__media c-accordion__media--has-overlay is-sticky is-active\">\n\n\t\t\t\t\t\t\t\t<div class=\"c-image front-h-left front-v-center main-h-full main-v-center r-none is-image\">\n\n\t\t\t\t\t<div class=\"c-image__media c-image__primary\">\n\t\t\t\t<img decoding=\"async\" class=\"c-image__src lazy\" loading=\"lazy\" src=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/08\/0-768x988.jpg\"  alt=\"0\" width=\"768\" height=\"988\"\/>\t\t\t<\/div>\n\t\t\n\t\t\n\t<\/div>\n\n\t\t\t\t\t\t\t\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n<div class=\"m-block  gt gb is-sticky l-content-simple-1\"  >\n\n\t\n\t\n\t<div class=\"m-block__container container\" style=\"\">\n\n\t\t<div class=\"l-heading text-left l-heading-v1\">\n\n\t\t\t    <div class=\"c-heading -h2 \">\n\t\t\n\t\t\n\t\t\t\t\t<h2  class=\"c-heading__title\">See how AutogenAI can transform your proposals.<\/h2>\t\t\n\t\t    <\/div>\n\n<div class=\"c-heading__description is-wysiwyg\">\n\t\t\t<p>Book a 30-minute demo with our legal sector specialists and discover how top-tier firms are winning more work, faster.<\/p>\n\t\t\t\t\t    <div class=\"c-block__btn\">\n\t\t\n\t\t\t<a href=\"\/apac\/book-a-demo\"  class=\"c-btn -normal -primary has-icon icon-right \"><span class=\"c-btn__inner\"><span class=\"c-btn__txt\">Book a Demo<\/span><span class=\"c-btn__ico\"><svg width=\"30\" height=\"30\" class=\"icon icon-lib-icon-arrow1 \" aria-hidden=\"true\" role=\"img\"><use xlink:href=\"#lib-icon-arrow1\"><\/use><\/svg><\/span><\/span><\/a>\n\t\t\n\t\t\t\n\t\t    <\/div>\n\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n\n\t\n<\/div>\n\n\n\n<div class=\"separators-custom-box  \"  >\n\n\t\n\t<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":0,"parent":722,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"content-type":"","inline_featured_image":false,"footnotes":""},"class_list":["post-4892","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>AI Tools for Legal | AutogenAI<\/title>\n<meta name=\"description\" content=\"AutogenAI for Legal helps law firms draft winning proposals, reduce partner hours, and deliver pitches 85% faster with structured, evidence-led content.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"AI Tools for Legal | AutogenAI\" \/>\n<meta property=\"og:description\" content=\"AutogenAI for Legal helps law firms draft winning proposals, reduce partner hours, and deliver pitches 85% faster with structured, evidence-led content.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/\" \/>\n<meta property=\"og:site_name\" content=\"AutogenAI APAC\" \/>\n<meta property=\"article:modified_time\" content=\"2025-09-02T14:10:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/09\/resizable_c8465690-51c6-4e3b-9af0-067a3fcd55b0.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"30 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/ai-for-legal\\\/\",\"url\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/ai-for-legal\\\/\",\"name\":\"AI Tools for Legal | AutogenAI\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/#website\"},\"datePublished\":\"2025-09-02T02:38:41+00:00\",\"dateModified\":\"2025-09-02T14:10:25+00:00\",\"description\":\"AutogenAI for Legal helps law firms draft winning proposals, reduce partner hours, and deliver pitches 85% faster with structured, evidence-led content.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/ai-for-legal\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/ai-for-legal\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/ai-for-legal\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sectors\",\"item\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/sectors\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Legal\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/#website\",\"url\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/\",\"name\":\"AutogenAI APAC\",\"description\":\"Win more business\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/autogenai.com\\\/apac\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"AI Tools for Legal | AutogenAI","description":"AutogenAI for Legal helps law firms draft winning proposals, reduce partner hours, and deliver pitches 85% faster with structured, evidence-led content.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/","og_locale":"en_US","og_type":"article","og_title":"AI Tools for Legal | AutogenAI","og_description":"AutogenAI for Legal helps law firms draft winning proposals, reduce partner hours, and deliver pitches 85% faster with structured, evidence-led content.","og_url":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/","og_site_name":"AutogenAI APAC","article_modified_time":"2025-09-02T14:10:25+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/autogenai.com\/apac\/wp-content\/uploads\/sites\/5\/2025\/09\/resizable_c8465690-51c6-4e3b-9af0-067a3fcd55b0.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"30 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/","url":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/","name":"AI Tools for Legal | AutogenAI","isPartOf":{"@id":"https:\/\/autogenai.com\/apac\/#website"},"datePublished":"2025-09-02T02:38:41+00:00","dateModified":"2025-09-02T14:10:25+00:00","description":"AutogenAI for Legal helps law firms draft winning proposals, reduce partner hours, and deliver pitches 85% faster with structured, evidence-led content.","breadcrumb":{"@id":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/autogenai.com\/apac\/sectors\/ai-for-legal\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/autogenai.com\/apac\/"},{"@type":"ListItem","position":2,"name":"Sectors","item":"https:\/\/autogenai.com\/apac\/sectors\/"},{"@type":"ListItem","position":3,"name":"Legal"}]},{"@type":"WebSite","@id":"https:\/\/autogenai.com\/apac\/#website","url":"https:\/\/autogenai.com\/apac\/","name":"AutogenAI APAC","description":"Win more business","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/autogenai.com\/apac\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/4892","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/comments?post=4892"}],"version-history":[{"count":5,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/4892\/revisions"}],"predecessor-version":[{"id":4960,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/4892\/revisions\/4960"}],"up":[{"embeddable":true,"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/pages\/722"}],"wp:attachment":[{"href":"https:\/\/autogenai.com\/apac\/wp-json\/wp\/v2\/media?parent=4892"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}